{"id":1,"count":1,"description":"","link":"https:\/\/jinga.ir\/en\/category\/%d8%af%d8%b3%d8%aa%d9%87-%d8%a8%d9%86%d8%af%db%8c-%d9%86%d8%b4%d8%af%d9%87\/","name":"\u062f\u0633\u062a\u0647 \u0628\u0646\u062f\u06cc \u0646\u0634\u062f\u0647","slug":"%d8%af%d8%b3%d8%aa%d9%87-%d8%a8%d9%86%d8%af%db%8c-%d9%86%d8%b4%d8%af%d9%87","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.4 (Yoast SEO v24.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u062f\u0633\u062a\u0647 \u0628\u0646\u062f\u06cc \u0646\u0634\u062f\u0647 Archives - \u062c\u06cc\u0646\u06af\u0627 | \u0646\u0648\u0634\u06cc\u062f\u0646\u06cc \u06af\u0627\u0632\u062f\u0627\u0631 \u0648 \u0622\u0628\u0645\u06cc\u0648\u0647 \u062c\u06cc\u0646\u06af\u0627<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jinga.ir\/en\/category\/%d8%af%d8%b3%d8%aa%d9%87-%d8%a8%d9%86%d8%af%db%8c-%d9%86%d8%b4%d8%af%d9%87\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u062f\u0633\u062a\u0647 \u0628\u0646\u062f\u06cc \u0646\u0634\u062f\u0647 Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jinga.ir\/en\/category\/%d8%af%d8%b3%d8%aa%d9%87-%d8%a8%d9%86%d8%af%db%8c-%d9%86%d8%b4%d8%af%d9%87\/\" \/>\n<meta property=\"og:site_name\" content=\"\u062c\u06cc\u0646\u06af\u0627 | \u0646\u0648\u0634\u06cc\u062f\u0646\u06cc \u06af\u0627\u0632\u062f\u0627\u0631 \u0648 \u0622\u0628\u0645\u06cc\u0648\u0647 \u062c\u06cc\u0646\u06af\u0627\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/jinga.ir\/en\/category\/%d8%af%d8%b3%d8%aa%d9%87-%d8%a8%d9%86%d8%af%db%8c-%d9%86%d8%b4%d8%af%d9%87\/\",\"url\":\"https:\/\/jinga.ir\/en\/category\/%d8%af%d8%b3%d8%aa%d9%87-%d8%a8%d9%86%d8%af%db%8c-%d9%86%d8%b4%d8%af%d9%87\/\",\"name\":\"\u062f\u0633\u062a\u0647 \u0628\u0646\u062f\u06cc \u0646\u0634\u062f\u0647 Archives - \u062c\u06cc\u0646\u06af\u0627 | \u0646\u0648\u0634\u06cc\u062f\u0646\u06cc \u06af\u0627\u0632\u062f\u0627\u0631 \u0648 \u0622\u0628\u0645\u06cc\u0648\u0647 \u062c\u06cc\u0646\u06af\u0627\",\"isPartOf\":{\"@id\":\"https:\/\/jinga.ir\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/jinga.ir\/en\/category\/%d8%af%d8%b3%d8%aa%d9%87-%d8%a8%d9%86%d8%af%db%8c-%d9%86%d8%b4%d8%af%d9%87\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jinga.ir\/en\/category\/%d8%af%d8%b3%d8%aa%d9%87-%d8%a8%d9%86%d8%af%db%8c-%d9%86%d8%b4%d8%af%d9%87\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/jinga.ir\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u062f\u0633\u062a\u0647 \u0628\u0646\u062f\u06cc \u0646\u0634\u062f\u0647\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jinga.ir\/en\/#website\",\"url\":\"https:\/\/jinga.ir\/en\/\",\"name\":\"\u062c\u06cc\u0646\u06af\u0627 | \u0646\u0648\u0634\u06cc\u062f\u0646\u06cc \u06af\u0627\u0632\u062f\u0627\u0631 \u0648 \u0622\u0628\u0645\u06cc\u0648\u0647 \u062c\u06cc\u0646\u06af\u0627\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/jinga.ir\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jinga.ir\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jinga.ir\/en\/#organization\",\"name\":\"\u062c\u06cc\u0646\u06af\u0627 | \u0646\u0648\u0634\u06cc\u062f\u0646\u06cc \u06af\u0627\u0632\u062f\u0627\u0631 \u0648 \u0622\u0628\u0645\u06cc\u0648\u0647 \u062c\u06cc\u0646\u06af\u0627\",\"url\":\"https:\/\/jinga.ir\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/jinga.ir\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/jinga.ir\/wp-content\/uploads\/2025\/02\/logo.png\",\"contentUrl\":\"https:\/\/jinga.ir\/wp-content\/uploads\/2025\/02\/logo.png\",\"width\":246,\"height\":100,\"caption\":\"\u062c\u06cc\u0646\u06af\u0627 | \u0646\u0648\u0634\u06cc\u062f\u0646\u06cc \u06af\u0627\u0632\u062f\u0627\u0631 \u0648 \u0622\u0628\u0645\u06cc\u0648\u0647 \u062c\u06cc\u0646\u06af\u0627\"},\"image\":{\"@id\":\"https:\/\/jinga.ir\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u062f\u0633\u062a\u0647 \u0628\u0646\u062f\u06cc \u0646\u0634\u062f\u0647 Archives - \u062c\u06cc\u0646\u06af\u0627 | \u0646\u0648\u0634\u06cc\u062f\u0646\u06cc \u06af\u0627\u0632\u062f\u0627\u0631 \u0648 \u0622\u0628\u0645\u06cc\u0648\u0647 \u062c\u06cc\u0646\u06af\u0627","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jinga.ir\/en\/category\/%d8%af%d8%b3%d8%aa%d9%87-%d8%a8%d9%86%d8%af%db%8c-%d9%86%d8%b4%d8%af%d9%87\/","og_locale":"en_US","og_type":"article","og_title":"\u062f\u0633\u062a\u0647 \u0628\u0646\u062f\u06cc \u0646\u0634\u062f\u0647 Archives","og_url":"https:\/\/jinga.ir\/en\/category\/%d8%af%d8%b3%d8%aa%d9%87-%d8%a8%d9%86%d8%af%db%8c-%d9%86%d8%b4%d8%af%d9%87\/","og_site_name":"\u062c\u06cc\u0646\u06af\u0627 | \u0646\u0648\u0634\u06cc\u062f\u0646\u06cc \u06af\u0627\u0632\u062f\u0627\u0631 \u0648 \u0622\u0628\u0645\u06cc\u0648\u0647 \u062c\u06cc\u0646\u06af\u0627","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jinga.ir\/en\/category\/%d8%af%d8%b3%d8%aa%d9%87-%d8%a8%d9%86%d8%af%db%8c-%d9%86%d8%b4%d8%af%d9%87\/","url":"https:\/\/jinga.ir\/en\/category\/%d8%af%d8%b3%d8%aa%d9%87-%d8%a8%d9%86%d8%af%db%8c-%d9%86%d8%b4%d8%af%d9%87\/","name":"\u062f\u0633\u062a\u0647 \u0628\u0646\u062f\u06cc \u0646\u0634\u062f\u0647 Archives - \u062c\u06cc\u0646\u06af\u0627 | \u0646\u0648\u0634\u06cc\u062f\u0646\u06cc \u06af\u0627\u0632\u062f\u0627\u0631 \u0648 \u0622\u0628\u0645\u06cc\u0648\u0647 \u062c\u06cc\u0646\u06af\u0627","isPartOf":{"@id":"https:\/\/jinga.ir\/en\/#website"},"breadcrumb":{"@id":"https:\/\/jinga.ir\/en\/category\/%d8%af%d8%b3%d8%aa%d9%87-%d8%a8%d9%86%d8%af%db%8c-%d9%86%d8%b4%d8%af%d9%87\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/jinga.ir\/en\/category\/%d8%af%d8%b3%d8%aa%d9%87-%d8%a8%d9%86%d8%af%db%8c-%d9%86%d8%b4%d8%af%d9%87\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jinga.ir\/en\/"},{"@type":"ListItem","position":2,"name":"\u062f\u0633\u062a\u0647 \u0628\u0646\u062f\u06cc \u0646\u0634\u062f\u0647"}]},{"@type":"WebSite","@id":"https:\/\/jinga.ir\/en\/#website","url":"https:\/\/jinga.ir\/en\/","name":"\u062c\u06cc\u0646\u06af\u0627 | \u0646\u0648\u0634\u06cc\u062f\u0646\u06cc \u06af\u0627\u0632\u062f\u0627\u0631 \u0648 \u0622\u0628\u0645\u06cc\u0648\u0647 \u062c\u06cc\u0646\u06af\u0627","description":"","publisher":{"@id":"https:\/\/jinga.ir\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jinga.ir\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/jinga.ir\/en\/#organization","name":"\u062c\u06cc\u0646\u06af\u0627 | \u0646\u0648\u0634\u06cc\u062f\u0646\u06cc \u06af\u0627\u0632\u062f\u0627\u0631 \u0648 \u0622\u0628\u0645\u06cc\u0648\u0647 \u062c\u06cc\u0646\u06af\u0627","url":"https:\/\/jinga.ir\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jinga.ir\/en\/#\/schema\/logo\/image\/","url":"https:\/\/jinga.ir\/wp-content\/uploads\/2025\/02\/logo.png","contentUrl":"https:\/\/jinga.ir\/wp-content\/uploads\/2025\/02\/logo.png","width":246,"height":100,"caption":"\u062c\u06cc\u0646\u06af\u0627 | \u0646\u0648\u0634\u06cc\u062f\u0646\u06cc \u06af\u0627\u0632\u062f\u0627\u0631 \u0648 \u0622\u0628\u0645\u06cc\u0648\u0647 \u062c\u06cc\u0646\u06af\u0627"},"image":{"@id":"https:\/\/jinga.ir\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jinga.ir\/en\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jinga.ir\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/jinga.ir\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/jinga.ir\/en\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}